{"id":76868,"date":"2021-06-01T11:18:40","date_gmt":"2021-06-01T09:18:40","guid":{"rendered":"https:\/\/www.cromology.com\/?page_id=76868"},"modified":"2021-06-07T15:57:10","modified_gmt":"2021-06-07T13:57:10","slug":"tollens","status":"publish","type":"page","link":"https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/","title":{"rendered":"Tollens"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;marque-header&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;fade-in&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;slow&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;marque-header-wrapper&#8221;]\n<div class=\"marque-background\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-76811\" src=\"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/06\/header-tollens.jpg\" alt=\"Tollens\" width=\"1215\" height=\"310\" srcset=\"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/06\/header-tollens.jpg 1215w, https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/06\/header-tollens-300x77.jpg 300w, https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/06\/header-tollens-1024x261.jpg 1024w, https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/06\/header-tollens-768x196.jpg 768w\" sizes=\"auto, (max-width: 1215px) 100vw, 1215px\" \/><\/div>\n<div class=\"marque-big\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-264\" src=\"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/05\/Tollens-big@2x-1.jpg\" alt=\"\" width=\"530\" height=\"197\" srcset=\"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/05\/Tollens-big@2x-1.jpg 530w, https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/05\/Tollens-big@2x-1-300x112.jpg 300w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/><\/div>\n<div class=\"toutes-marques\"><a href=\"https:\/\/www.cromology.com\/en\/group\/brands\/\">All brands<\/a><\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;marque-contenu&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h1>Tollens<\/h1>\n[\/vc_column_text][vc_column_text el_class=&#8221;marque-flag&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-228\" src=\"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/05\/french-flasg@2x.jpg\" alt=\"\" width=\"27\" height=\"18\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-229\" src=\"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/05\/italian-flag@2x.jpg\" alt=\"\" width=\"27\" height=\"18\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-230\" src=\"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/05\/spain-flag@2x.jpg\" alt=\"\" width=\"27\" height=\"18\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-227\" src=\"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/05\/belgium-flag@2x.jpg\" alt=\"\" width=\"27\" height=\"18\" \/>[\/vc_column_text][vc_column_text]Distributed in France, Italy, Spain, Belgium[\/vc_column_text][vc_column_text el_class=&#8221;-&#8220;]<strong>Born in 1748, Tollens is the oldest paint brand still in business. It is a historical reference and carries values of know-how, color expertise, performance and durability of products. <\/strong><\/p>\n<p>Tollens is widely distributed and supports professionals and individuals through its 170 Tollens Points of Sale, its e-commerce website and also thanks to the trust of a network of independent distributors, large DIY stores and building material stores. Tollens allows its customers to experience renewed products of exceptional quality while offering its personalized advice, it inspires everyone to give personality to living spaces and make them unique. Concerned about the community in which Tollens operates and sensitive to the cultural world, Tollens supports four museums in France by contributing to the chromatic scenography of exhibitions: Mus\u00e9e d&#8217;Orsay (Paris), Mus\u00e9e de l&#8217;Orangerie (Paris), Cit\u00e9 de l&#8217;Architecture et du Design (Paris) and Mus\u00e9e de la Piscine (Roubaix). Tollens also sponsors Urban Arts projects or local initiatives such as a shared contemporary art studio in the Pays de Gex region.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#eeeeee&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;marque-nav&#8221; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; color_override=&#8221;#ffffff&#8221; solid_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;none&#8221; text=&#8221;Tollens France&#8221; url=&#8221;https:\/\/www.tollens.com\/&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; color_override=&#8221;#ffffff&#8221; solid_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;none&#8221; text=&#8221;Tollens Spain&#8221; url=&#8221;https:\/\/www.tollens.es\/&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; color_override=&#8221;#ffffff&#8221; solid_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;none&#8221; text=&#8221;Tollens Italy&#8221; url=&#8221;http:\/\/www.tollens.it\/&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; color_override=&#8221;#ffffff&#8221; solid_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;none&#8221; text=&#8221;Tollens Belgium&#8221; url=&#8221;https:\/\/www.tollens.be\/&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]France e-commerce website[\/vc_column_text][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; color_override=&#8221;#ffffff&#8221; solid_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;none&#8221; text=&#8221;MyTollens.com&#8221; url=&#8221;https:\/\/my.tollens.com\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"[vc_row type=\"in_container\" full_screen_row_position=\"middle\" column_margin=\"default\" column_direction=\"default\" column_direction_tablet=\"default\" column_direction_phone=\"default\" scene_position=\"center\" text_color=\"dark\" text_align=\"left\" row_border_radius=\"none\" row_border_radius_applies=\"bg\" class=\"marque-header\" overlay_strength=\"0.3\" gradient_direction=\"left_to_right\" shape_divider_position=\"bottom\" bg_image_animation=\"fade-in\" parallax_bg=\"true\" parallax_bg_speed=\"slow\" shape_type=\"\"][vc_column column_padding=\"no-extra-padding\" column_padding_tablet=\"inherit\" column_padding_phone=\"inherit\" column_padding_position=\"all\" column_element_spacing=\"default\" background_color_opacity=\"1\" background_hover_color_opacity=\"1\" column_shadow=\"none\" column_border_radius=\"none\" column_link_target=\"_self\"...","protected":false},"author":5,"featured_media":0,"parent":76865,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-76868","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tollens | Cromology<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tollens | Cromology\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/\" \/>\n<meta property=\"og:site_name\" content=\"Cromology\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Cromology.group\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-07T13:57:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/1r7eqkbkdws.preview.infomaniak.website\/wp-content\/uploads\/2021\/06\/header-tollens.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cromology\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/group\\\/brands\\\/tollens\\\/\",\"url\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/group\\\/brands\\\/tollens\\\/\",\"name\":\"Tollens | Cromology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/group\\\/brands\\\/tollens\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/group\\\/brands\\\/tollens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cromology.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/header-tollens.jpg\",\"datePublished\":\"2021-06-01T09:18:40+00:00\",\"dateModified\":\"2021-06-07T13:57:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/group\\\/brands\\\/tollens\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cromology.com\\\/en\\\/group\\\/brands\\\/tollens\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/group\\\/brands\\\/tollens\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cromology.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/header-tollens.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cromology.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/header-tollens.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/group\\\/brands\\\/tollens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Group\",\"item\":\"https:\\\/\\\/1r7eqkbkdws.preview.infomaniak.website\\\/en\\\/group\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Brands\",\"item\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/group\\\/brands\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Tollens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/\",\"name\":\"Cromology\",\"description\":\"Prot\u00e9ger et colorer durablement les espaces de vie pour am\u00e9liorer le quotidien de chacun\u200b.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/#organization\",\"name\":\"Cromology\",\"url\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cromology.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-Cromology@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.cromology.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-Cromology@2x.png\",\"width\":243,\"height\":25,\"caption\":\"Cromology\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cromology.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Cromology.group\\\/\",\"https:\\\/\\\/x.com\\\/cromology\",\"https:\\\/\\\/www.instagram.com\\\/cromology_sas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXWP8nxxPJ5IgKmNErRw1KQ\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Cromology\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tollens | Cromology","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/","og_locale":"en_US","og_type":"article","og_title":"Tollens | Cromology","og_url":"https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/","og_site_name":"Cromology","article_publisher":"https:\/\/www.facebook.com\/Cromology.group\/","article_modified_time":"2021-06-07T13:57:10+00:00","og_image":[{"url":"https:\/\/1r7eqkbkdws.preview.infomaniak.website\/wp-content\/uploads\/2021\/06\/header-tollens.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@cromology","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/","url":"https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/","name":"Tollens | Cromology","isPartOf":{"@id":"https:\/\/www.cromology.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/#primaryimage"},"image":{"@id":"https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/06\/header-tollens.jpg","datePublished":"2021-06-01T09:18:40+00:00","dateModified":"2021-06-07T13:57:10+00:00","breadcrumb":{"@id":"https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/#primaryimage","url":"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/06\/header-tollens.jpg","contentUrl":"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/06\/header-tollens.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cromology.com\/en\/group\/brands\/tollens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cromology.com\/en\/"},{"@type":"ListItem","position":2,"name":"Group","item":"https:\/\/1r7eqkbkdws.preview.infomaniak.website\/en\/group\/"},{"@type":"ListItem","position":3,"name":"Brands","item":"https:\/\/www.cromology.com\/en\/group\/brands\/"},{"@type":"ListItem","position":4,"name":"Tollens"}]},{"@type":"WebSite","@id":"https:\/\/www.cromology.com\/en\/#website","url":"https:\/\/www.cromology.com\/en\/","name":"Cromology","description":"Prot\u00e9ger et colorer durablement les espaces de vie pour am\u00e9liorer le quotidien de chacun\u200b.","publisher":{"@id":"https:\/\/www.cromology.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cromology.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cromology.com\/en\/#organization","name":"Cromology","url":"https:\/\/www.cromology.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cromology.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/05\/Logo-Cromology@2x.png","contentUrl":"https:\/\/www.cromology.com\/wp-content\/uploads\/2021\/05\/Logo-Cromology@2x.png","width":243,"height":25,"caption":"Cromology"},"image":{"@id":"https:\/\/www.cromology.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Cromology.group\/","https:\/\/x.com\/cromology","https:\/\/www.instagram.com\/cromology_sas\/","https:\/\/www.youtube.com\/channel\/UCXWP8nxxPJ5IgKmNErRw1KQ","https:\/\/fr.wikipedia.org\/wiki\/Cromology"]}]}},"_links":{"self":[{"href":"https:\/\/www.cromology.com\/en\/wp-json\/wp\/v2\/pages\/76868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cromology.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cromology.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cromology.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cromology.com\/en\/wp-json\/wp\/v2\/comments?post=76868"}],"version-history":[{"count":0,"href":"https:\/\/www.cromology.com\/en\/wp-json\/wp\/v2\/pages\/76868\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.cromology.com\/en\/wp-json\/wp\/v2\/pages\/76865"}],"wp:attachment":[{"href":"https:\/\/www.cromology.com\/en\/wp-json\/wp\/v2\/media?parent=76868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}